{"id":328,"date":"2020-12-20T11:41:55","date_gmt":"2020-12-20T16:41:55","guid":{"rendered":"https:\/\/climatetoolkit.org\/?p=328"},"modified":"2025-06-18T16:12:44","modified_gmt":"2025-06-18T20:12:44","slug":"how-to-reduce-carbon-emissions-energy-management-and-audits","status":"publish","type":"post","link":"https:\/\/climatetoolkit.org\/pt\/how-to-reduce-carbon-emissions-energy-management-and-audits\/","title":{"rendered":"Como reduzir as emiss\u00f5es de carbono: Gest\u00e3o e auditorias energ\u00e9ticas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Atualmente, somos confrontados com decis\u00f5es que ir\u00e3o inibir ou promover a nossa sa\u00fade e a do nosso ambiente. Todas as mudan\u00e7as que possa efetuar na sua organiza\u00e7\u00e3o podem ter um impacto positivo no ambiente e nas pessoas que o rodeiam. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mitigar as emiss\u00f5es de carbono de toda uma organiza\u00e7\u00e3o ou jardim bot\u00e2nico pode parecer incrivelmente dif\u00edcil, mas a chave \u00e9 saber por onde come\u00e7ar - e este guia ajud\u00e1-lo-\u00e1 a come\u00e7ar! O Climate Toolkit sugere que comece a gerir a sua energia atrav\u00e9s da realiza\u00e7\u00e3o de uma auditoria, estabelecendo uma linha de base e identificando as ferramentas mais eficazes para a mitiga\u00e7\u00e3o. Este guia explicar\u00e1 um resumo do que s\u00e3o os sistemas de gest\u00e3o de energia sustent\u00e1vel e as auditorias energ\u00e9ticas, por que raz\u00e3o utilizar ambos, exemplos de outros jardins que adoptam a energia l\u00edquida zero e outras recomenda\u00e7\u00f5es.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Tr\u00eas \u00e2mbitos de emiss\u00f5es:<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/ghgprotocol.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Protocolo de Gases com Efeito de Estufa do Instituto de Recursos Mundiais<\/a> categoriza as fontes de emiss\u00f5es com tr\u00eas \u00e2mbitos para efeitos de rastreio, que fornecem um bom modelo a n\u00edvel organizacional para come\u00e7ar a considerar o seu impacto nas emiss\u00f5es. Como parafraseado a partir de <a href=\"https:\/\/ghgprotocol.org\/sites\/default\/files\/standards_supporting\/FAQ.pd\" target=\"_blank\" rel=\"noreferrer noopener\">o seu s\u00edtio Web<\/a>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>\u00c2mbito 1<\/strong> cobre diretamente <strong>emiss\u00f5es<\/strong> de fontes pr\u00f3prias ou controladas. <\/li><li><strong>\u00c2mbito 2<\/strong> abrange os servi\u00e7os indirectos <strong>emiss\u00f5es<\/strong> da produ\u00e7\u00e3o de eletricidade comprada, vapor, aquecimento e arrefecimento consumidos pela empresa declarante. <\/li><li><strong>\u00c2mbito 3<\/strong> inclui todos os outros custos indirectos <strong>emiss\u00f5es<\/strong> que ocorrem na cadeia de valor de uma empresa.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Embora todos os tr\u00eas \u00e2mbitos devam ser monitorizados e auditados para uma abordagem abrangente \u00e0 gest\u00e3o da energia, as emiss\u00f5es dos \u00e2mbitos 1 e 2 constituem um bom ponto de partida para a expans\u00e3o e representam as emiss\u00f5es que est\u00e3o mais ao alcance de uma organiza\u00e7\u00e3o para monitorizar e controlar, e ser\u00e3o principalmente discutidas no resto deste artigo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>O que \u00e9 um sistema de gest\u00e3o de energia?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A gest\u00e3o de energia pode ser definida como \"o processo de monitoriza\u00e7\u00e3o, controlo ou conserva\u00e7\u00e3o de energia num edif\u00edcio ou organiza\u00e7\u00e3o\". O consumo de energia de todas as empresas \u00e9 medido de alguma forma, mesmo que seja apenas para gerar fatura\u00e7\u00e3o de eletricidade ou outros servi\u00e7os, mas o objetivo aqui \u00e9 utilizar um sistema para <em>reduzir<\/em> utiliza\u00e7\u00e3o de energia e emiss\u00f5es de carbono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A gest\u00e3o sustent\u00e1vel da energia adopta uma abordagem regenerativa para considerar a utiliza\u00e7\u00e3o de energia, na medida em que n\u00e3o considera apenas os componentes individuais, mas o sistema global. Pense na gest\u00e3o sustent\u00e1vel da energia como um ciclo cont\u00ednuo - um processo cont\u00ednuo para avaliar e melhorar o desempenho - em vez de um objetivo finito. O primeiro passo de um sistema de gest\u00e3o de energia sustent\u00e1vel \u00e9 completar <strong>uma auditoria energ\u00e9tica<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Por onde come\u00e7ar: Uma auditoria energ\u00e9tica<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Uma auditoria energ\u00e9tica \u00e9 uma avalia\u00e7\u00e3o da utiliza\u00e7\u00e3o atual de energia. Empresas externas ou o seu fornecedor de servi\u00e7os p\u00fablicos podem efetuar auditorias energ\u00e9ticas e avaliar o sistema energ\u00e9tico do seu campus. A auditoria comercial m\u00e9dia custar\u00e1 entre $1,000 e $15,000, dependendo da dimens\u00e3o do campus e da complexidade da auditoria. As auditorias realizadas internamente tamb\u00e9m podem ser \u00fateis, desde que o pessoal disponha de tempo suficiente para efetuar essa an\u00e1lise.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-default\"\/>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-color has-background\" style=\"background-color:#e1feff;\"><font class=\"has-medium-font-size\">Entre as ferramentas de autoan\u00e1lise, a ferramenta da EPA <a href=\"https:\/\/www.epa.gov\/file\/simplified-ghg-emissions-calculator\" style=\"text-decoration: underline;\"><u><strong>Calculadora Simplificada de Emiss\u00f5es de Gases com Efeito de Estufa<\/strong><\/u><\/a> \u00e9 uma ferramenta abrangente que qualquer organiza\u00e7\u00e3o pode utilizar para come\u00e7ar. O Phipps Conservatory est\u00e1 a planear come\u00e7ar a utilizar esta ferramenta para o seu pr\u00f3prio acompanhamento interno. Se a sua organiza\u00e7\u00e3o quiser juntar-se a n\u00f3s, experimente esta ferramenta ou uma ferramenta semelhante, <a href=\"mailto:climatetoolkit@phipps.conservatory.org\" style=\"text-decoration: underline;\"><u><strong>entre em contacto connosco<\/strong><\/u><\/a>A sua experi\u00eancia ser\u00e1 valiosa para ajudar a determinar as melhores pr\u00e1ticas a adotar por outras hortas.<\/font><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-default\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">As auditorias energ\u00e9ticas podem avaliar sistemas espec\u00edficos de utiliza\u00e7\u00e3o de energia, envolventes de edif\u00edcios, sistemas de constru\u00e7\u00e3o, opera\u00e7\u00f5es e procedimentos de manuten\u00e7\u00e3o ou hor\u00e1rios de constru\u00e7\u00e3o. Quando se procura reduzir as emiss\u00f5es de carbono, uma auditoria energ\u00e9tica pode ser \u00fatil para mostrar quais os edif\u00edcios e \u00e1reas que est\u00e3o a utilizar as quantidades mais significativas de energia e onde as redu\u00e7\u00f5es direcionadas podem ter os maiores benef\u00edcios. A auditoria criar\u00e1 um mapa de utiliza\u00e7\u00e3o de energia e de emiss\u00f5es <strong>linha de base <\/strong>que pode ser utilizado como padr\u00e3o para compara\u00e7\u00e3o ap\u00f3s a implementa\u00e7\u00e3o das altera\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com base nos dados, os auditores criam recomenda\u00e7\u00f5es em mat\u00e9ria de custos e energia. A auditoria cria uma linha de base de utiliza\u00e7\u00e3o de energia e dados financeiros que \u00e9 depois comparada com as recomenda\u00e7\u00f5es. As auditorias energ\u00e9ticas permitem poupar dinheiro ao ajudar a dar prioridade aos \"frutos mais f\u00e1ceis\", ou \u00e0s interven\u00e7\u00f5es que podem ser efectuadas e que ter\u00e3o o maior impacto imediato. \u00c0 medida que avan\u00e7a nas suas recomenda\u00e7\u00f5es de auditoria, as poupan\u00e7as podem estar relacionadas com o longo prazo e, nalguns casos, pode n\u00e3o haver poupan\u00e7as para al\u00e9m da sa\u00fade das pessoas e do planeta - mas todas s\u00e3o importantes para abordar estas quest\u00f5es de forma abrangente e fornecer um exemplo de alto n\u00edvel para outros.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Exemplos de gest\u00e3o de energia em jardins p\u00fablicos<\/strong>:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Duas organiza\u00e7\u00f5es que reduziram com \u00eaxito as suas emiss\u00f5es de gases com efeito de estufa s\u00e3o o New York Botanical Garden (NYBG) e o Phipps Conservatory and Botanical Gardens. O NYBG criou um sistema de energia sustent\u00e1vel que mede consistentemente e reduz ainda mais as suas emiss\u00f5es de carbono. O Phipps criou uma plataforma de energia sustent\u00e1vel que reduziu significativamente as suas emiss\u00f5es de carbono e envolveu ativamente os funcion\u00e1rios.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"670\" height=\"348\" src=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden.jpg\" alt=\"\" class=\"wp-image-359\" srcset=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden.jpg 670w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-300x156.jpg 300w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-100x52.jpg 100w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-150x78.jpg 150w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-200x104.jpg 200w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-450x234.jpg 450w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/NYG-Botanical-Garden-600x312.jpg 600w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A investiga\u00e7\u00e3o apoia a utiliza\u00e7\u00e3o de auditorias energ\u00e9ticas e de sistemas de gest\u00e3o de energia para uma redu\u00e7\u00e3o global das emiss\u00f5es de carbono. Atualmente, o NYBG baseia-se fortemente numa auditoria anual de carbono e energia para determinar as \u00e1reas de elevadas emiss\u00f5es de carbono e melhorou os seus sistemas energ\u00e9ticos convertendo-os para um sistema de aquecimento a g\u00e1s natural mais limpo, actualizando os seus sistemas de ar condicionado, renovando o seu sistema de ventila\u00e7\u00e3o e participando em programas de gest\u00e3o da procura e de sensibiliza\u00e7\u00e3o. Atrav\u00e9s destes esfor\u00e7os, o NYBG reduziu a sua pegada de carbono em 53% por p\u00e9 quadrado, poupando ao jardim cerca de $300.000 por ano. Investiram num compromisso a longo prazo para melhorar consistentemente o seu sistema de energia para reduzir as suas emiss\u00f5es de carbono.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/CSL-Phipps-1-1024x481.jpg\" alt=\"\" class=\"wp-image-390\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a sua expans\u00e3o em v\u00e1rias fases, a Phipps trabalhou com o entendimento de que a sa\u00fade humana e ambiental s\u00e3o interdependentes. Sabiam que os edif\u00edcios novos e renovados tinham de ser bonitos, funcionais e eficientes. Os tr\u00eas projectos mais recentes, o Center for Sustainable Landscapes, o Nature Lab e o Exhibit Staging Center, s\u00e3o todos positivos em termos l\u00edquidos, o que significa que as energias renov\u00e1veis no local geram mais eletricidade do que a necess\u00e1ria para os edif\u00edcios. Desde essa expans\u00e3o, a Phipps reduziu as suas emiss\u00f5es globais de di\u00f3xido de carbono em 56% por p\u00e9 quadrado e utiliza agora 100% de eletricidade renov\u00e1vel que \u00e9 produzida no local com energia solar e e\u00f3lica ou comprada no exterior.  Se as organiza\u00e7\u00f5es n\u00e3o puderem produzir energia renov\u00e1vel no campus, podem ser adquiridos Certificados de Energia Renov\u00e1vel junto do seu fornecedor de eletricidade. Embora n\u00e3o seja t\u00e3o eficaz no combate \u00e0s altera\u00e7\u00f5es clim\u00e1ticas como a produ\u00e7\u00e3o no local, a utiliza\u00e7\u00e3o de RECs pode apoiar a energia renov\u00e1vel e a inova\u00e7\u00e3o e empregos ecol\u00f3gicos. A compra de Certificados de Energia Renov\u00e1vel \u00e9 um primeiro passo na dire\u00e7\u00e3o certa para se comprometer com a redu\u00e7\u00e3o das emiss\u00f5es de carbono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os meses, a equipa de instala\u00e7\u00f5es da Phipps recolhe dados sobre g\u00e1s, eletricidade e energia e compara-os com o desempenho anterior para identificar irregularidades e anomalias. Al\u00e9m disso, um comit\u00e9 que representa cada um dos departamentos da institui\u00e7\u00e3o re\u00fane-se para analisar os dados e partilhar ideias de altera\u00e7\u00f5es operacionais que possam aumentar a efici\u00eancia e reduzir as emiss\u00f5es.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Recomenda\u00e7\u00f5es<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">O Climate Toolkit d\u00e1 tr\u00eas sugest\u00f5es a todos os jardins bot\u00e2nicos e organiza\u00e7\u00f5es que queiram reduzir as suas emiss\u00f5es de carbono.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Realizar uma auditoria energ\u00e9tica<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira recomenda\u00e7\u00e3o \u00e9 efetuar uma auditoria e determinar as emiss\u00f5es de carbono e os valores de refer\u00eancia da energia. \u00c9 \u00fatil identificar os sectores que mais contribuem para as emiss\u00f5es, o que muitas vezes lhe d\u00e1 um bom ponto de partida.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Fale com o seu fornecedor de energia<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">A segunda recomenda\u00e7\u00e3o \u00e9 falar com o seu fornecedor de energia sobre a compra de energia renov\u00e1vel. Atualmente, a Phipps n\u00e3o produz eletricidade suficiente para satisfazer a procura de todo o campus, mas pode comprar energia renov\u00e1vel para compensar o que n\u00e3o \u00e9 produzido no campus. O seu fornecedor de eletricidade poder\u00e1 sugerir op\u00e7\u00f5es de energia renov\u00e1vel dispon\u00edveis ou outras solu\u00e7\u00f5es.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Examinar as emiss\u00f5es de carbono a n\u00edvel operacional<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">A recomenda\u00e7\u00e3o final \u00e9 avaliar e analisar as emiss\u00f5es de carbono a n\u00edvel operacional. Os incentivos e programas podem ajudar os funcion\u00e1rios, h\u00f3spedes e outras partes interessadas a reduzir as suas emiss\u00f5es de carbono. Na Phipps, os funcion\u00e1rios que se deslocam de forma sustent\u00e1vel (de bicicleta, a p\u00e9, em transportes p\u00fablicos ou em carpooling) s\u00e3o compensados financeiramente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Refer\u00eancias <\/strong><\/h4>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h5 class=\"wp-block-heading\">Literatura acad\u00e9mica que explica a gest\u00e3o da energia<\/h5>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/ghgprotocol.org\/sites\/default\/files\/standards_supporting\/FAQ.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Objectivos de emiss\u00e3o <\/a>   <\/li><li><a href=\"https:\/\/citeseerx.ist.psu.edu\/viewdoc\/download?doi=10.1.1.469.8641&amp;rep=rep1&amp;type=pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sistemas de gest\u00e3o de energia na Su\u00e9cia<\/a><\/li><li><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0921344917302021?casa_token=G6xjJ6_Di-cAAAAA:HgTtpigS1uHYszgauzkxpMVWKf525zhp8_BWdmx7iijuFZOhnCLJs31fJUPioEr3lpEJ0jKQB0o\" target=\"_blank\" rel=\"noreferrer noopener\">Empresas transformadoras da Mal\u00e1sia<\/a><\/li><li><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0959652615007891?casa_token=DUYe-d-BKfgAAAAA:9bnANf5LHr7Z4NVkSdU0IMaLdWkx80WeBEkfSesyosFzLAszEqvdFbT164HOhaZcLcatVp62sA0#bib65\" target=\"_blank\" rel=\"noreferrer noopener\">Uma revis\u00e3o sistem\u00e1tica das estrat\u00e9gias de gest\u00e3o da energia<\/a><\/li><li><a href=\"https:\/\/www.iso.org\/standard\/69426.html\">Sistemas de gest\u00e3o de energia pelas Corpora\u00e7\u00f5es Internacionais de Normaliza\u00e7\u00e3o<\/a><\/li><\/ul>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplos bot\u00e2nicos de sistemas energ\u00e9ticos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/be-exchange.org\/wp content\/uploads\/2018\/12\/20181206NYBG_Web.pdf\">Jardim Bot\u00e2nico de Nova Iorque<\/a><\/li><li><a href=\"https:\/\/www.bgci.org\/wp\/wp-content\/uploads\/2020\/04\/ReviewMedRes.pdf\">Uma an\u00e1lise t\u00e9cnica da pr\u00e1tica da sustentabilidade em jardins bot\u00e2nicos<\/a><\/li><li><a href=\"https:\/\/living-future.org\/lbc\/case-studies\/phipps-center-for-sustainable-landscapes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro Phipps para paisagens sustent\u00e1veis <\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-living-future-org\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/living-future.org\/lbc\/case-studies\/phipps-center-for-sustainable-landscapes\/\n<\/div><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Recursos de auditoria<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/nayaenergy.com\/difference-between-energy-audit-and-energy-management\/\" target=\"_blank\" rel=\"noreferrer noopener\">A diferen\u00e7a entre auditoria energ\u00e9tica e gest\u00e3o da energia <\/a><\/li><li><a href=\"https:\/\/www.pnnl.gov\/main\/publications\/external\/technical_reports\/PNNL-20956.pdf\">Um guia para a auditoria energ\u00e9tica<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Atualmente, somos confrontados com decis\u00f5es que ir\u00e3o inibir ou promover a nossa sa\u00fade e a do nosso ambiente. Todas as mudan\u00e7as que se podem efetuar na organiza\u00e7\u00e3o podem ter um impacto positivo no ambiente e nas pessoas que a rodeiam. Mitigar as emiss\u00f5es de carbono para ...<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/climatetoolkit.org\/pt\/how-to-reduce-carbon-emissions-energy-management-and-audits\/\"> <span class=\"screen-reader-text\">Como reduzir as emiss\u00f5es de carbono: Gest\u00e3o e auditorias energ\u00e9ticas<\/span> Ler mais \"<\/a><\/p>","protected":false},"author":2,"featured_media":384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit\" \/>\n<meta property=\"og:description\" content=\"We are currently faced with decisions that will either inhibit or advance the health of ourselves and our environment. Every change that you can make in your organization can positively impact the surrounding environment and people. Mitigating carbon emissions for &hellip; How to Reduce Carbon Emissions: Energy Management and Audits Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/climatetoolkit.org\/pt\/how-to-reduce-carbon-emissions-energy-management-and-audits\/\" \/>\n<meta property=\"og:site_name\" content=\"The Climate Toolkit\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-20T16:41:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T20:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joe reed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"joe reed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/\"},\"author\":{\"name\":\"joe reed\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/person\\\/0a315cfe2d4239376531ced9d06c441c\"},\"headline\":\"How to Reduce Carbon Emissions: Energy Management and Audits\",\"datePublished\":\"2020-12-20T16:41:55+00:00\",\"dateModified\":\"2025-06-18T20:12:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/\"},\"wordCount\":1325,\"publisher\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/switch-main_1400_660auto_s_c1-1.jpg\",\"articleSection\":[\"Energy\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/\",\"name\":\"How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/switch-main_1400_660auto_s_c1-1.jpg\",\"datePublished\":\"2020-12-20T16:41:55+00:00\",\"dateModified\":\"2025-06-18T20:12:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/switch-main_1400_660auto_s_c1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/switch-main_1400_660auto_s_c1-1.jpg\",\"width\":1400,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/how-to-reduce-carbon-emissions-energy-management-and-audits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/climatetoolkit.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Reduce Carbon Emissions: Energy Management and Audits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#website\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/\",\"name\":\"The Climate Toolkit\",\"description\":\"For Museums, Gardens and Zoos\",\"publisher\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/climatetoolkit.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\",\"name\":\"The Climate Toolkit\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/C_logo.png\",\"contentUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/C_logo.png\",\"width\":512,\"height\":512,\"caption\":\"The Climate Toolkit\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/person\\\/0a315cfe2d4239376531ced9d06c441c\",\"name\":\"joe reed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"caption\":\"joe reed\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_PT","og_type":"article","og_title":"How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit","og_description":"We are currently faced with decisions that will either inhibit or advance the health of ourselves and our environment. Every change that you can make in your organization can positively impact the surrounding environment and people. Mitigating carbon emissions for &hellip; How to Reduce Carbon Emissions: Energy Management and Audits Read More &raquo;","og_url":"https:\/\/climatetoolkit.org\/pt\/how-to-reduce-carbon-emissions-energy-management-and-audits\/","og_site_name":"The Climate Toolkit","article_published_time":"2020-12-20T16:41:55+00:00","article_modified_time":"2025-06-18T20:12:44+00:00","og_image":[{"width":1400,"height":660,"url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg","type":"image\/jpeg"}],"author":"joe reed","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"joe reed","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#article","isPartOf":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/"},"author":{"name":"joe reed","@id":"https:\/\/climatetoolkit.org\/#\/schema\/person\/0a315cfe2d4239376531ced9d06c441c"},"headline":"How to Reduce Carbon Emissions: Energy Management and Audits","datePublished":"2020-12-20T16:41:55+00:00","dateModified":"2025-06-18T20:12:44+00:00","mainEntityOfPage":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/"},"wordCount":1325,"publisher":{"@id":"https:\/\/climatetoolkit.org\/#organization"},"image":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#primaryimage"},"thumbnailUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg","articleSection":["Energy"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/","url":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/","name":"How to Reduce Carbon Emissions: Energy Management and Audits - The Climate Toolkit","isPartOf":{"@id":"https:\/\/climatetoolkit.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#primaryimage"},"image":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#primaryimage"},"thumbnailUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg","datePublished":"2020-12-20T16:41:55+00:00","dateModified":"2025-06-18T20:12:44+00:00","breadcrumb":{"@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#primaryimage","url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg","contentUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1.jpg","width":1400,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/climatetoolkit.org\/how-to-reduce-carbon-emissions-energy-management-and-audits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/climatetoolkit.org\/"},{"@type":"ListItem","position":2,"name":"How to Reduce Carbon Emissions: Energy Management and Audits"}]},{"@type":"WebSite","@id":"https:\/\/climatetoolkit.org\/#website","url":"https:\/\/climatetoolkit.org\/","name":"O kit de ferramentas para o clima","description":"Para museus, jardins e jardins zool\u00f3gicos","publisher":{"@id":"https:\/\/climatetoolkit.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/climatetoolkit.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/climatetoolkit.org\/#organization","name":"O kit de ferramentas para o clima","url":"https:\/\/climatetoolkit.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/climatetoolkit.org\/#\/schema\/logo\/image\/","url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/05\/C_logo.png","contentUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/05\/C_logo.png","width":512,"height":512,"caption":"The Climate Toolkit"},"image":{"@id":"https:\/\/climatetoolkit.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/climatetoolkit.org\/#\/schema\/person\/0a315cfe2d4239376531ced9d06c441c","name":"joe reed","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","caption":"joe reed"}}]}},"author_meta":{"display_name":"joe reed","author_link":"https:\/\/climatetoolkit.org\/pt\/author\/joe\/"},"featured_img":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/12\/switch-main_1400_660auto_s_c1-1-300x141.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/climatetoolkit.org\/pt\/blog-category\/energy\/\" class=\"advgb-post-tax-term\">Energy<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Energy<\/span>"]}},"comment_count":0,"relative_dates":{"created":"Publicado 6 anos h\u00e1","modified":"Atualizado 1 ano h\u00e1"},"absolute_dates":{"created":"Publicado em Dezembro 20, 2020","modified":"Atualizado em Junho 18, 2025"},"absolute_dates_time":{"created":"Publicado em Dezembro 20, 2020 11:41 am","modified":"Atualizado em Junho 18, 2025 4:12 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/posts\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":1,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"predecessor-version":[{"id":4534,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/posts\/328\/revisions\/4534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/media\/384"}],"wp:attachment":[{"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/climatetoolkit.org\/pt\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}