{"id":1675,"date":"2022-05-05T12:43:59","date_gmt":"2022-05-05T16:43:59","guid":{"rendered":"https:\/\/climatetoolkit.org\/?p=1675"},"modified":"2025-06-18T16:12:39","modified_gmt":"2025-06-18T20:12:39","slug":"the-climate-toolkit-climate-leadership-meets-collaboration","status":"publish","type":"post","link":"https:\/\/climatetoolkit.org\/es\/the-climate-toolkit-climate-leadership-meets-collaboration\/","title":{"rendered":"Climate Toolkit: el liderazgo clim\u00e1tico se une a la colaboraci\u00f3n"},"content":{"rendered":"<h6 class=\"wp-block-heading\">Por Richard V. Piacentini<\/h6>\n\n\n\n<p>La crisis clim\u00e1tica es uno de los mayores retos a los que se enfrenta el mundo hoy en d\u00eda, y los directivos y el personal de nuestras instituciones culturales -desde los altos cargos hasta los miembros del personal de gesti\u00f3n de instalaciones, comunicaci\u00f3n, conservaci\u00f3n y otras disciplinas- pueden desempe\u00f1ar un papel esencial a la hora de abordarla. Gracias a la acci\u00f3n colectiva de jardines bot\u00e1nicos, museos y zool\u00f3gicos de todo el mundo, nuestras instituciones pueden abordar estos problemas a una escala sin precedentes. Podemos potenciar a\u00fan m\u00e1s esta acci\u00f3n animando a nuestros electores colectivos -m\u00e1s de 500 millones de visitantes al a\u00f1o- a que act\u00faen ellos mismos. La transformaci\u00f3n no es f\u00e1cil, pero resulta m\u00e1s sencilla cuando las organizaciones trabajan juntas para ayudarse mutuamente. Aqu\u00ed es donde entra en juego la Caja de Herramientas del Clima. <\/p>\n\n\n\n<p>Climate Toolkit (climatetoolkit.org) se cre\u00f3 como una oportunidad de colaboraci\u00f3n y un centro de recursos para las organizaciones culturales basadas en colecciones que deseen compartir informaci\u00f3n, asesorarse mutuamente, aprender a abordar en\u00e9rgicamente el cambio clim\u00e1tico, una oportunidad de colaboraci\u00f3n y un centro de recursos para las organizaciones culturales basadas en colecciones que deseen compartir informaci\u00f3n, asesorarse mutuamente, aprender a abordar en\u00e9rgicamente el cambio clim\u00e1tico e inspirar a las comunidades a las que sirven para que sigan su ejemplo. El conjunto de herramientas abarca 31 objetivos para abordar el cambio clim\u00e1tico dentro de las categor\u00edas de energ\u00eda, servicios alimentarios, agua, transporte, residuos, paisajes y horticultura, inversiones, compromiso interno y externo, e investigaci\u00f3n. Hasta la fecha, en el Conjunto de herramientas sobre el clima participan 55 organizaciones, que atienden a m\u00e1s de 43.457.000 visitantes anuales. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png\" alt=\"\" class=\"wp-image-1678\" width=\"544\" height=\"433\" srcset=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png 707w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-300x238.png 300w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-100x79.png 100w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-150x119.png 150w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-200x159.png 200w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-450x358.png 450w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas-600x477.png 600w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/><figcaption><em>Las nueve principales \u00e1reas de inter\u00e9s de la Caja de Herramientas del Clima.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>El conjunto de herramientas se cre\u00f3 teniendo en cuenta que cada organizaci\u00f3n es diferente, cada comunidad es diferente y cada biorregi\u00f3n es diferente, y que cada una tendr\u00e1 que priorizar las \u00e1reas que le resulten m\u00e1s importantes abordar. Esto significa que las iniciativas de sostenibilidad ser\u00e1n tan singulares como cada instituci\u00f3n. De hecho, deben reflejar las condiciones locales reales de la regi\u00f3n de la instituci\u00f3n, si quieren tener un efecto multiplicador en las comunidades a las que sirven. <\/p>\n\n\n\n<p>En muchos a\u00f1os de encabezar iniciativas de sostenibilidad en Phipps, hemos comprobado que no podemos combatir el cambio clim\u00e1tico mediante la acci\u00f3n de una sola instituci\u00f3n o un solo individuo. Tenemos que trabajar juntos. Nuestros departamentos de educaci\u00f3n, instalaciones, sostenibilidad, marketing, horticultura y otros han sido esenciales para ayudar a establecer las mejores pr\u00e1cticas, y han seguido abordando el cambio clim\u00e1tico sin dejar de ser activos en la comunidad. Si las instituciones p\u00fablicas y sus profesionales trabajan juntos colectivamente, podemos compartir informaci\u00f3n valiosa y modelos de \u00e9xito, ayudarnos a responder a las preguntas de los dem\u00e1s y apoyarnos mutuamente en nuestros viajes hacia la sostenibilidad. <\/p>\n\n\n\n<p>El Climate Toolkit ayuda a los participantes a alcanzar sus objetivos iniciando debates a trav\u00e9s de varias plataformas diferentes. El Climate Toolkit realiza entrevistas educativas sobre iniciativas de sostenibilidad con instituciones que han alcanzado sus objetivos, elabora gu\u00edas sobre temas espec\u00edficos relacionados con el clima y organiza seminarios web interactivos para mantener la conversaci\u00f3n. El Climate Toolkit trabaja directamente con las instituciones para crear art\u00edculos informativos que describan el proceso de realizaci\u00f3n de esfuerzos espec\u00edficos, entre ellos<br>por d\u00f3nde empezar, qu\u00e9 esperar y c\u00f3mo superar retos espec\u00edficos. <\/p>\n\n\n\n<p>Nuestras instituciones p\u00fablicas han estado trabajando duro para alcanzar sus objetivos y marcar la diferencia en sus comunidades, y nuestros conocimientos colectivos y nuestra interconexi\u00f3n ya est\u00e1n demostrando ser nuestros mayores recursos. Algunos ejemplos de contenido reciente incluyen recursos para ayudar a reducir el consumo de pl\u00e1sticos, una gu\u00eda sobre c\u00f3mo completar auditor\u00edas energ\u00e9ticas, una entrevista sobre los beneficios de los equipos verdes, c\u00f3mo comprar energ\u00eda renovable, \u00a1y mucho m\u00e1s! <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture.jpg\" alt=\"\" class=\"wp-image-1676\" width=\"568\" height=\"316\" srcset=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture.jpg 684w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-300x167.jpg 300w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-680x380.jpg 680w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-100x56.jpg 100w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-150x83.jpg 150w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-200x111.jpg 200w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-450x250.jpg 450w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/About-Us-Picture-600x333.jpg 600w\" sizes=\"(max-width: 568px) 100vw, 568px\" \/><figcaption><em>Captura de pantalla del primer seminario web sobre herramientas clim\u00e1ticas.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Los seminarios web tambi\u00e9n se crean para facilitar el debate en directo, responder a las preguntas que puedan tener las instituciones y presentar nueva informaci\u00f3n. Queremos que nuestros recursos sean accesibles a todas las instituciones p\u00fablicas. Todos los seminarios web, art\u00edculos, gu\u00edas y dem\u00e1s recursos son p\u00fablicos y gratuitos para todas las instituciones, incluso para las que no tienen acceso a ellos.<br>que a\u00fan no forman parte del Conjunto de herramientas sobre el clima. Para ayudar a proseguir el debate sobre la acci\u00f3n clim\u00e1tica, la Caja de Herramientas del Clima cuenta con numerosas herramientas para ayudar a los participantes a conectarse y plantear preguntas. Tambi\u00e9n se ha creado recientemente un servidor de listas para permitir conversaciones privadas sobre los retos de la sostenibilidad, para que nuestros participantes se conecten r\u00e1pidamente a trav\u00e9s de diferentes zonas horarias, y para presentar preguntas a nuestras instituciones sobre esfuerzos espec\u00edficos relacionados con el clima. <\/p>\n\n\n\n<p>El Climate Toolkit fomenta el debate y la conversaci\u00f3n a todos los niveles, incluidos invitados, miembros de la junta directiva, donantes y empleados. El Climate Toolkit tambi\u00e9n est\u00e1 trabajando diligentemente para iniciar conversaciones sobre el cambio clim\u00e1tico con nuestros j\u00f3venes en el \u00e1rea de Pittsburgh: se ha puesto en marcha un Comit\u00e9 Asesor Juvenil sobre el Clima formado por 20 estudiantes locales de secundaria y universitarios para fomentar el di\u00e1logo y la acci\u00f3n sobre el clima como modelo para otros. Con el tiempo, esperamos ayudar a otras instituciones a crear comit\u00e9s juveniles similares que puedan conectarse entre s\u00ed a trav\u00e9s del Conjunto de Herramientas. <\/p>\n\n\n\n<p>Tambi\u00e9n se cre\u00f3 un comit\u00e9 de asesoramiento t\u00e9cnico para ayudar a revisar y dar su opini\u00f3n sobre las piezas informativas y las gu\u00edas que crea el Conjunto de herramientas. A medida que el conjunto de herramientas se extienda internacionalmente, y a trav\u00e9s de zonas horarias y biorregiones, crearemos grupos de trabajo adicionales para ayudar a garantizar que la informaci\u00f3n sea relevante para todas estas instituciones.<\/p>\n\n\n\n<p><br>Los jardines bot\u00e1nicos, los zool\u00f3gicos y los museos son instituciones p\u00fablicas de confianza que han evolucionado para satisfacer las necesidades de sus biorregiones y comunidades espec\u00edficas, lo que supone una oportunidad de liderazgo dentro de sus comunidades en relaci\u00f3n con las cuestiones de salud humana y medioambiental. Colectivamente, las instituciones p\u00fablicas pueden tener un profundo impacto en la lucha contra el cambio clim\u00e1tico, llegando a la ra\u00edz del problema, abordando los estilos de vida humanos y trabajando para lograr un cambio duradero. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-1024x682.jpg\" alt=\"\" class=\"wp-image-1680\" width=\"512\" height=\"341\" srcset=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-1024x682.jpg 1024w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-300x200.jpg 300w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-768x512.jpg 768w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-1536x1024.jpg 1536w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-2048x1365.jpg 2048w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-100x67.jpg 100w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-150x100.jpg 150w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-200x133.jpg 200w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-450x300.jpg 450w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-600x400.jpg 600w, https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Collage-Hi-900x600.jpg 900w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><figcaption><em>(en el sentido de las agujas del reloj, desde arriba a la izquierda): Jard\u00edn Bot\u00e1nico de Santa B\u00e1rbara, Museo de la Ciencia de Minnesota, Morton Arboretum y Jard\u00edn Bot\u00e1nico de la Costa de Maine.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Los responsables de cada jard\u00edn, museo y zoo deben abordar las causas profundas de los problemas medioambientales espec\u00edficos a los que se enfrentan nuestras comunidades, y deben hacerlo de una forma que pueda reproducirse y transmitirse a los visitantes.  Como profesionales de las instalaciones, ustedes trabajan en numerosas \u00e1reas que pueden abordar directamente el cambio clim\u00e1tico, incluida la gesti\u00f3n de residuos y el consumo de energ\u00eda y agua, que son \u00e1reas cr\u00edticas para su instituci\u00f3n. Tienen una oportunidad \u00fanica de mirar dentro de sus operaciones y crear un cambio que puede reducir significativamente las emisiones de carbono en su campus e inspirar a sus visitantes. Cuando te conviertes en administrador de la sostenibilidad, puedes abordar cuestiones vitales al tiempo que sirves de ejemplo para que otros cambien su forma de interactuar con el resto del mundo. <\/p>\n\n\n\n<p>Hay muchas formas de participar en nuestro trabajo si su instituci\u00f3n a\u00fan no est\u00e1 preparada para unirse al Climate Toolkit. Por ejemplo, puede visitar climatetoolkit.org y suscribirse a nuestro bolet\u00edn, que le mantendr\u00e1 informado sobre nuevos art\u00edculos, pr\u00f3ximos seminarios web y otras actividades. Cuando est\u00e9 preparado, nuestro equipo estar\u00e1 encantado de ayudarle a registrar su instituci\u00f3n en el Conjunto de herramientas y a elegir el \u00e1rea de inter\u00e9s que m\u00e1s le convenga. Estamos deseando seguir colaborando: no hay l\u00edmite a lo que podemos conseguir juntos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Por Richard V. Piacentini La crisis clim\u00e1tica es uno de los mayores retos a los que se enfrenta el mundo hoy en d\u00eda, y la direcci\u00f3n y el personal de nuestras instituciones culturales -desde altos cargos hasta miembros del personal de gesti\u00f3n de instalaciones, comunicaciones, ...<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/climatetoolkit.org\/es\/the-climate-toolkit-climate-leadership-meets-collaboration\/\"> <span class=\"screen-reader-text\">Climate Toolkit: el liderazgo clim\u00e1tico se une a la colaboraci\u00f3n<\/span> Leer m\u00e1s \"<\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1675","post","type-post","status-publish","format-standard","hentry","category-energy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit\" \/>\n<meta property=\"og:description\" content=\"By Richard V. Piacentini The climate crisis is one of the biggest challenges facing the world today, and the leadership and staff of our cultural institutions\u2014 from senior leaders to staff members in facilities management, communications, curatorial, and other disciplines\u2014 &hellip; The Climate Toolkit- Climate Leadership Meets Collaboration Leer m\u00e1s \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/climatetoolkit.org\/es\/the-climate-toolkit-climate-leadership-meets-collaboration\/\" \/>\n<meta property=\"og:site_name\" content=\"The Climate Toolkit\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T16:43:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T20:12:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"joe reed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"joe reed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/\"},\"author\":{\"name\":\"joe reed\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/person\\\/0a315cfe2d4239376531ced9d06c441c\"},\"headline\":\"The Climate Toolkit- Climate Leadership Meets Collaboration\",\"datePublished\":\"2022-05-05T16:43:59+00:00\",\"dateModified\":\"2025-06-18T20:12:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/\"},\"wordCount\":1104,\"publisher\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Focus-areas.png\",\"articleSection\":[\"Energy\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/\",\"name\":\"The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Focus-areas.png\",\"datePublished\":\"2022-05-05T16:43:59+00:00\",\"dateModified\":\"2025-06-18T20:12:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Focus-areas.png\",\"contentUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Focus-areas.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/the-climate-toolkit-climate-leadership-meets-collaboration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/climatetoolkit.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Climate Toolkit- Climate Leadership Meets Collaboration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#website\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/\",\"name\":\"The Climate Toolkit\",\"description\":\"For Museums, Gardens and Zoos\",\"publisher\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/climatetoolkit.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#organization\",\"name\":\"The Climate Toolkit\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/C_logo.png\",\"contentUrl\":\"https:\\\/\\\/climatetoolkit.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/C_logo.png\",\"width\":512,\"height\":512,\"caption\":\"The Climate Toolkit\"},\"image\":{\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/climatetoolkit.org\\\/#\\\/schema\\\/person\\\/0a315cfe2d4239376531ced9d06c441c\",\"name\":\"joe reed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g\",\"caption\":\"joe reed\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit","og_description":"By Richard V. Piacentini The climate crisis is one of the biggest challenges facing the world today, and the leadership and staff of our cultural institutions\u2014 from senior leaders to staff members in facilities management, communications, curatorial, and other disciplines\u2014 &hellip; The Climate Toolkit- Climate Leadership Meets Collaboration Leer m\u00e1s \u00bb","og_url":"https:\/\/climatetoolkit.org\/es\/the-climate-toolkit-climate-leadership-meets-collaboration\/","og_site_name":"The Climate Toolkit","article_published_time":"2022-05-05T16:43:59+00:00","article_modified_time":"2025-06-18T20:12:39+00:00","og_image":[{"width":707,"height":562,"url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png","type":"image\/png"}],"author":"joe reed","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"joe reed","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#article","isPartOf":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/"},"author":{"name":"joe reed","@id":"https:\/\/climatetoolkit.org\/#\/schema\/person\/0a315cfe2d4239376531ced9d06c441c"},"headline":"The Climate Toolkit- Climate Leadership Meets Collaboration","datePublished":"2022-05-05T16:43:59+00:00","dateModified":"2025-06-18T20:12:39+00:00","mainEntityOfPage":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/"},"wordCount":1104,"publisher":{"@id":"https:\/\/climatetoolkit.org\/#organization"},"image":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#primaryimage"},"thumbnailUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png","articleSection":["Energy"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/","url":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/","name":"The Climate Toolkit- Climate Leadership Meets Collaboration - The Climate Toolkit","isPartOf":{"@id":"https:\/\/climatetoolkit.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#primaryimage"},"image":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#primaryimage"},"thumbnailUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png","datePublished":"2022-05-05T16:43:59+00:00","dateModified":"2025-06-18T20:12:39+00:00","breadcrumb":{"@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#primaryimage","url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png","contentUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2022\/05\/Focus-areas.png"},{"@type":"BreadcrumbList","@id":"https:\/\/climatetoolkit.org\/the-climate-toolkit-climate-leadership-meets-collaboration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/climatetoolkit.org\/"},{"@type":"ListItem","position":2,"name":"The Climate Toolkit- Climate Leadership Meets Collaboration"}]},{"@type":"WebSite","@id":"https:\/\/climatetoolkit.org\/#website","url":"https:\/\/climatetoolkit.org\/","name":"Herramientas para el clima","description":"Para museos, jardines y zool\u00f3gicos","publisher":{"@id":"https:\/\/climatetoolkit.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/climatetoolkit.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/climatetoolkit.org\/#organization","name":"Herramientas para el clima","url":"https:\/\/climatetoolkit.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/climatetoolkit.org\/#\/schema\/logo\/image\/","url":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/05\/C_logo.png","contentUrl":"https:\/\/climatetoolkit.org\/wp-content\/uploads\/2020\/05\/C_logo.png","width":512,"height":512,"caption":"The Climate Toolkit"},"image":{"@id":"https:\/\/climatetoolkit.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/climatetoolkit.org\/#\/schema\/person\/0a315cfe2d4239376531ced9d06c441c","name":"joe reed","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/472f195403d80a13cf2167242ca383d8b44ece2a427beed29cba86949c90ae13?s=96&d=mm&r=g","caption":"joe reed"}}]}},"author_meta":{"display_name":"joe reed","author_link":"https:\/\/climatetoolkit.org\/es\/author\/joe\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/climatetoolkit.org\/es\/blog-category\/energy\/\" class=\"advgb-post-tax-term\">Energy<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Energy<\/span>"]}},"comment_count":0,"relative_dates":{"created":"Publicado 4 a\u00f1os hace","modified":"Actualizado 11 meses hace"},"absolute_dates":{"created":"Publicado el mayo 5, 2022","modified":"Actualizado el junio 18, 2025"},"absolute_dates_time":{"created":"Publicado el mayo 5, 2022 12:43 pm","modified":"Actualizado el junio 18, 2025 4:12 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/posts\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/comments?post=1675"}],"version-history":[{"count":1,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/posts\/1675\/revisions"}],"predecessor-version":[{"id":4514,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/posts\/1675\/revisions\/4514"}],"wp:attachment":[{"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/media?parent=1675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/categories?post=1675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/climatetoolkit.org\/es\/wp-json\/wp\/v2\/tags?post=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}